{"id":2731,"count":1,"description":"","link":"https:\/\/www.racba.org\/en\/autor-publicacio\/martorell-i-casado-lidia-separata\/","name":"Martorell i Casad\u00f3, L\u00eddia (Separata)","slug":"martorell-i-casado-lidia-separata","taxonomy":"autor-publicacio","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.racba.org\/en\/wp-json\/wp\/v2\/autor-publicacio\/2731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.racba.org\/en\/wp-json\/wp\/v2\/autor-publicacio"}],"about":[{"href":"https:\/\/www.racba.org\/en\/wp-json\/wp\/v2\/taxonomies\/autor-publicacio"}],"wp:post_type":[{"href":"https:\/\/www.racba.org\/en\/wp-json\/wp\/v2\/publicacio?autor-publicacio=2731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}