{"id":12344,"date":"2021-01-01T00:00:00","date_gmt":"2020-12-31T23:00:00","guid":{"rendered":"http:\/\/novaweb.racba.org\/publicacio\/el-secreter-de-josep-francesc-de-caramany\/"},"modified":"2024-10-23T18:08:45","modified_gmt":"2024-10-23T16:08:45","slug":"el-secreter-de-josep-francesc-de-caramany","status":"publish","type":"publicacio","link":"https:\/\/www.racba.org\/es\/publicacio\/el-secreter-de-josep-francesc-de-caramany\/","title":{"rendered":"El secreter de Josep Francesc de Caramany"},"content":{"rendered":"<p>Discurs d&#8217;ingr\u00e9s \u00abEl secreter de Josep Francesc de Caramany\u00bb. Inclou discurs de resposta de Pilar V\u00e9lez (32 p\u00e0g., 23 cm.). 10,00 \u20ac.<\/p>\n","protected":false},"featured_media":12345,"template":"","tipus":[2319],"autor-publicacio":[2800],"class_list":["post-12344","publicacio","type-publicacio","status-publish","has-post-thumbnail","hentry","tipus-discurs-dingres","autor-publicacio-piera-miquel-monica"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/publicacio\/12344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/publicacio"}],"about":[{"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/types\/publicacio"}],"version-history":[{"count":1,"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/publicacio\/12344\/revisions"}],"predecessor-version":[{"id":25752,"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/publicacio\/12344\/revisions\/25752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/media\/12345"}],"wp:attachment":[{"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/media?parent=12344"}],"wp:term":[{"taxonomy":"tipus","embeddable":true,"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/tipus?post=12344"},{"taxonomy":"autor-publicacio","embeddable":true,"href":"https:\/\/www.racba.org\/es\/wp-json\/wp\/v2\/autor-publicacio?post=12344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}